{"id":72299,"date":"2025-09-25T16:20:54","date_gmt":"2025-09-25T19:20:54","guid":{"rendered":"https:\/\/insurancecorp.com.br\/pt\/?p=72299"},"modified":"2025-09-25T16:20:54","modified_gmt":"2025-09-25T19:20:54","slug":"alper-marca-presenca-no-encontro-de-empresarios-do-setcemg","status":"publish","type":"post","link":"https:\/\/insurancecorp.com.br\/pt\/2025\/09\/25\/alper-marca-presenca-no-encontro-de-empresarios-do-setcemg\/","title":{"rendered":"Alper marca presen\u00e7a no Encontro de Empres\u00e1rios do Setcemg"},"content":{"rendered":"<p>A Alper Seguros est\u00e1 presente no\u00a0Encontro de Empres\u00e1rios do SETCEMG, que acontece hoje, no Est\u00e1dio Mineir\u00e3o, em Belo Horizonte. Realizado pelo Sindicato das Empresas de Transportes de Cargas e Log\u00edstica de Minas Gerais (SETCEMG), o evento re\u00fane cerca de 180 empres\u00e1rios do setor de log\u00edstica para um dia de debates, palestras e networking.<\/p>\n<p>A filial da Alper em Belo Horizonte representa a\u00a0Unidade de Neg\u00f3cios Alper Cargo, refor\u00e7ando o compromisso da companhia em estreitar relacionamentos estrat\u00e9gicos e ampliar sua presen\u00e7a no mercado mineiro.<\/p>\n<p>Durante toda a programa\u00e7\u00e3o, especialistas discutem os principais desafios e perspectivas para o transporte e a log\u00edstica no Brasil, em um espa\u00e7o de troca de conhecimento e gera\u00e7\u00e3o de oportunidades.<\/p>\n<p>A Alper Seguros participa com a presen\u00e7a de\u00a0Alessandro Barletta, Gustavo Silva Albergaria Kneipp, B\u00e1rbara Ribeiro e Luis De Caprio.<\/p>\n<p><strong>Evento:<\/strong>\u00a0<em>Encontro de Empres\u00e1rios do Setcemg<\/em><\/p>\n<p><strong>Data:<\/strong>\u00a025 de setembro de 2025 (quinta-feira)<br \/>\n<strong>Hor\u00e1rio:<\/strong>\u00a013h30 \u00e0s 22h<br \/>\n<strong>Local:<\/strong>\u00a0Est\u00e1dio Mineir\u00e3o \u2013 Av. Ant\u00f4nio Abrah\u00e3o Caram, 1001, Belo Horizonte<br \/>\n<strong>P\u00fablico:<\/strong>\u00a0Exclusivo para representantes de empresas associadas e apoiadores do Setcemg<\/p>\n<p><strong>Loures Comunica\u00e7\u00e3o<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Alper Seguros est\u00e1 presente no\u00a0Encontro de Empres\u00e1rios do SETCEMG, que acontece hoje, no Est\u00e1dio Mineir\u00e3o, em Belo Horizonte. Realizado pelo Sindicato das Empresas de Transportes de Cargas e Log\u00edstica de Minas Gerais (SETCEMG), o evento re\u00fane cerca de 180 empres\u00e1rios do setor de log\u00edstica para um dia de debates, palestras e networking. A filial [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":67284,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[8525],"tags":[8606,13339,3919,6112,3918,15311],"jetpack_featured_media_url":"https:\/\/insurancecorp.com.br\/pt\/wp-content\/uploads\/2025\/05\/Design-sem-nome-5-2-e1758828015868.png","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v14.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Alper marca presen\u00e7a no Encontro de Empres\u00e1rios do Setcemg | Revista Insurance Corp | PT-BR<\/title>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<meta name=\"googlebot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta name=\"bingbot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/insurancecorp.com.br\/pt\/2025\/09\/25\/alper-marca-presenca-no-encontro-de-empresarios-do-setcemg\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alper marca presen\u00e7a no Encontro de Empres\u00e1rios do Setcemg | Revista Insurance Corp | PT-BR\" \/>\n<meta property=\"og:description\" content=\"A Alper Seguros est\u00e1 presente no\u00a0Encontro de Empres\u00e1rios do SETCEMG, que acontece hoje, no Est\u00e1dio Mineir\u00e3o, em Belo Horizonte. Realizado pelo Sindicato das Empresas de Transportes de Cargas e Log\u00edstica de Minas Gerais (SETCEMG), o evento re\u00fane cerca de 180 empres\u00e1rios do setor de log\u00edstica para um dia de debates, palestras e networking. A filial [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/insurancecorp.com.br\/pt\/2025\/09\/25\/alper-marca-presenca-no-encontro-de-empresarios-do-setcemg\/\" \/>\n<meta property=\"og:site_name\" content=\"Revista Insurance Corp | PT-BR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RevistaInsuranceCorp\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-25T19:20:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/insurancecorp.com.br\/pt\/wp-content\/uploads\/2025\/05\/Design-sem-nome-5-2-e1758828015868.png\" \/>\n\t<meta property=\"og:image:width\" content=\"6912\" \/>\n\t<meta property=\"og:image:height\" content=\"2540\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#organization\",\"name\":\"Revista Insurance Corp\",\"url\":\"https:\/\/insurancecorp.com.br\/pt\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/RevistaInsuranceCorp\/\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#logo\",\"inLanguage\":\"pt-BR\",\"url\":\"\",\"caption\":\"Revista Insurance Corp\"},\"image\":{\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#website\",\"url\":\"https:\/\/insurancecorp.com.br\/pt\/\",\"name\":\"Revista Insurance Corp | PT-BR\",\"description\":\"A \\u00fanica revista bil\\u00edngue voltada ao mercado de seguro.\",\"publisher\":{\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/insurancecorp.com.br\/pt\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/2025\/09\/25\/alper-marca-presenca-no-encontro-de-empresarios-do-setcemg\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/insurancecorp.com.br\/pt\/wp-content\/uploads\/2025\/05\/Design-sem-nome-5-2-e1758828015868.png\",\"width\":6912,\"height\":2540},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/2025\/09\/25\/alper-marca-presenca-no-encontro-de-empresarios-do-setcemg\/#webpage\",\"url\":\"https:\/\/insurancecorp.com.br\/pt\/2025\/09\/25\/alper-marca-presenca-no-encontro-de-empresarios-do-setcemg\/\",\"name\":\"Alper marca presen\\u00e7a no Encontro de Empres\\u00e1rios do Setcemg | Revista Insurance Corp | PT-BR\",\"isPartOf\":{\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/2025\/09\/25\/alper-marca-presenca-no-encontro-de-empresarios-do-setcemg\/#primaryimage\"},\"datePublished\":\"2025-09-25T19:20:54+00:00\",\"dateModified\":\"2025-09-25T19:20:54+00:00\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/insurancecorp.com.br\/pt\/2025\/09\/25\/alper-marca-presenca-no-encontro-de-empresarios-do-setcemg\/\"]}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/2025\/09\/25\/alper-marca-presenca-no-encontro-de-empresarios-do-setcemg\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/2025\/09\/25\/alper-marca-presenca-no-encontro-de-empresarios-do-setcemg\/#webpage\"},\"author\":{\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#\/schema\/person\/1b69c8cf325f0b7167f1b171f52df4af\"},\"headline\":\"Alper marca presen\\u00e7a no Encontro de Empres\\u00e1rios do Setcemg\",\"datePublished\":\"2025-09-25T19:20:54+00:00\",\"dateModified\":\"2025-09-25T19:20:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/2025\/09\/25\/alper-marca-presenca-no-encontro-de-empresarios-do-setcemg\/#webpage\"},\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#organization\"},\"image\":{\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/2025\/09\/25\/alper-marca-presenca-no-encontro-de-empresarios-do-setcemg\/#primaryimage\"},\"keywords\":\"Alper,empres\\u00e1rios,encontro,marca,presen\\u00e7a,setcemg\",\"articleSection\":\"Alper Seguros\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/insurancecorp.com.br\/pt\/2025\/09\/25\/alper-marca-presenca-no-encontro-de-empresarios-do-setcemg\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#\/schema\/person\/1b69c8cf325f0b7167f1b171f52df4af\",\"name\":\"Publica\\u00e7\\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/17226f1f60486eb25d4c6b301ffed37f?s=96&d=mm&r=g\",\"caption\":\"Publica\\u00e7\\u00e3o\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/posts\/72299"}],"collection":[{"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/comments?post=72299"}],"version-history":[{"count":1,"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/posts\/72299\/revisions"}],"predecessor-version":[{"id":72300,"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/posts\/72299\/revisions\/72300"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/media\/67284"}],"wp:attachment":[{"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/media?parent=72299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/categories?post=72299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/tags?post=72299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}