{"id":55465,"date":"2024-06-06T15:59:08","date_gmt":"2024-06-06T18:59:08","guid":{"rendered":"https:\/\/insurancecorp.com.br\/pt\/?p=55465"},"modified":"2024-06-06T17:04:37","modified_gmt":"2024-06-06T20:04:37","slug":"mdrt-realiza-reuniao-anual-abordando-ia-no-planejamento-financeiro","status":"publish","type":"post","link":"https:\/\/insurancecorp.com.br\/pt\/2024\/06\/06\/mdrt-realiza-reuniao-anual-abordando-ia-no-planejamento-financeiro\/","title":{"rendered":"MDRT realiza Reuni\u00e3o Anual abordando IA"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Na pr\u00f3xima semana, de 09 a 12 de junho, acontece a 97\u00aa edi\u00e7\u00e3o da Reuni\u00e3o Anual MDRT (Annual Meeting MDRT), principal evento da associa\u00e7\u00e3o que re\u00fane especialistas em seguro de vida e planejamento financeiro de mais de 200 pa\u00edses. O evento deste ano em Vancouver, no Canad\u00e1, deve ter participa\u00e7\u00e3o recorde de profissionais brasileiros.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ser\u00e3o quatro dias de atividades, com mais de 100 palestrantes e mais de 120 sess\u00f5es de palestras. &#8220;A Reuni\u00e3o Anual do MDRT re\u00fane milhares de membros de todo o mundo para criar um evento exclusivo como nenhum outro, que estimula o crescimento atrav\u00e9s da aprendizagem, networking e partilha de ideias inovadoras. Os participantes ouvem palestrantes inspiradores, aprendem ideias de algumas das melhores mentes do mundo e compartilham suas melhores pr\u00e1ticas e inova\u00e7\u00f5es com colegas para ajudar a alcan\u00e7ar novos n\u00edveis de sucesso&#8221;, defende Felipe Sousa (foto), presidente da MDRT Brasil (Country Chair Brazil). &#8220;O evento refor\u00e7a aos membros do MDRT a import\u00e2ncia de serem indiv\u00edduos completos, melhorando suas vidas tanto pessoal quanto profissionalmente&#8221;, incentiva.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O tema deste ano ser\u00e1 intelig\u00eancia artificial no desenvolvimento do planejamento financeiro. &#8220;Diversas palestras ter\u00e3o como foco o uso da tecnologia para ajudar o corretor na hora de elaborar propostas, ap\u00f3lices, e cuidar do cliente de maneira mais eficiente. Veremos como isso pode ser utilizado at\u00e9 mesmo na subscri\u00e7\u00e3o dos seguros e redu\u00e7\u00e3o do risco&#8221;, adianta.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Com o aumento da participa\u00e7\u00e3o de brasileiros na entidade, a maior parte das palestras e todas as sess\u00f5es da plataforma principal ter\u00e3o tradu\u00e7\u00e3o para portugu\u00eas. &#8220;Muitos brasileiros s\u00e3o esperados como first-timer, ou seja, participantes pela primeira vez no MDRT, por isso este investimento no p\u00fablico. Temos a expectativa de realizar um evento muito especial, sem precedentes&#8221;.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Felipe destaca que, al\u00e9m do evento em si, um grande atrativo \u00e9 estar em uma das mais bonitas de todo o mundo. &#8220;Vancouver \u00e9 muito preparada na quest\u00e3o de turismo, qualidade de com\u00e9rcios e pessoas O Canad\u00e1 \u00e9 um pa\u00eds muito receptivo, especialmente aos brasileiros, por isso os participantes ir\u00e3o agregar experi\u00eancia tanto profissional como pessoal&#8221;, ressalta o presidente.<\/span><\/p>\n<p><strong>Ruco Comunica\u00e7\u00e3o\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na pr\u00f3xima semana, de 09 a 12 de junho, acontece a 97\u00aa edi\u00e7\u00e3o da Reuni\u00e3o Anual MDRT (Annual Meeting MDRT), principal evento da associa\u00e7\u00e3o que re\u00fane especialistas em seguro de vida e planejamento financeiro de mais de 200 pa\u00edses. O evento deste ano em Vancouver, no Canad\u00e1, deve ter participa\u00e7\u00e3o recorde de profissionais brasileiros. Ser\u00e3o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":55472,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[11005],"tags":[11006,1334,9492,2950,11007,1018],"jetpack_featured_media_url":"https:\/\/insurancecorp.com.br\/pt\/wp-content\/uploads\/2024\/06\/MDRT.png","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v14.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>MDRT realiza Reuni\u00e3o Anual abordando IA | Revista Insurance Corp | PT-BR<\/title>\n<meta name=\"description\" content=\"Evento que acontece de 09 a 12 de junho, em Vancouver, espera participa\u00e7\u00e3o recorde de brasileiros. Confira mais informa\u00e7\u00f5es em nosso site.\" \/>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<meta name=\"googlebot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta name=\"bingbot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/insurancecorp.com.br\/pt\/2024\/06\/06\/mdrt-realiza-reuniao-anual-abordando-ia-no-planejamento-financeiro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MDRT realiza Reuni\u00e3o Anual abordando IA | Revista Insurance Corp | PT-BR\" \/>\n<meta property=\"og:description\" content=\"Evento que acontece de 09 a 12 de junho, em Vancouver, espera participa\u00e7\u00e3o recorde de brasileiros. Confira mais informa\u00e7\u00f5es em nosso site.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/insurancecorp.com.br\/pt\/2024\/06\/06\/mdrt-realiza-reuniao-anual-abordando-ia-no-planejamento-financeiro\/\" \/>\n<meta property=\"og:site_name\" content=\"Revista Insurance Corp | PT-BR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RevistaInsuranceCorp\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-06T18:59:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-06T20:04:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/insurancecorp.com.br\/pt\/wp-content\/uploads\/2024\/06\/MDRT-1024x681.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"681\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#organization\",\"name\":\"Revista Insurance Corp\",\"url\":\"https:\/\/insurancecorp.com.br\/pt\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/RevistaInsuranceCorp\/\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#logo\",\"inLanguage\":\"pt-BR\",\"url\":\"\",\"caption\":\"Revista Insurance Corp\"},\"image\":{\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#website\",\"url\":\"https:\/\/insurancecorp.com.br\/pt\/\",\"name\":\"Revista Insurance Corp | PT-BR\",\"description\":\"A \\u00fanica revista bil\\u00edngue voltada ao mercado de seguro.\",\"publisher\":{\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/insurancecorp.com.br\/pt\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/2024\/06\/06\/mdrt-realiza-reuniao-anual-abordando-ia-no-planejamento-financeiro\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/insurancecorp.com.br\/pt\/wp-content\/uploads\/2024\/06\/MDRT.png\",\"width\":1351,\"height\":898},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/2024\/06\/06\/mdrt-realiza-reuniao-anual-abordando-ia-no-planejamento-financeiro\/#webpage\",\"url\":\"https:\/\/insurancecorp.com.br\/pt\/2024\/06\/06\/mdrt-realiza-reuniao-anual-abordando-ia-no-planejamento-financeiro\/\",\"name\":\"MDRT realiza Reuni\\u00e3o Anual abordando IA | Revista Insurance Corp | PT-BR\",\"isPartOf\":{\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/2024\/06\/06\/mdrt-realiza-reuniao-anual-abordando-ia-no-planejamento-financeiro\/#primaryimage\"},\"datePublished\":\"2024-06-06T18:59:08+00:00\",\"dateModified\":\"2024-06-06T20:04:37+00:00\",\"description\":\"Evento que acontece de 09 a 12 de junho, em Vancouver, espera participa\\u00e7\\u00e3o recorde de brasileiros. Confira mais informa\\u00e7\\u00f5es em nosso site.\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/insurancecorp.com.br\/pt\/2024\/06\/06\/mdrt-realiza-reuniao-anual-abordando-ia-no-planejamento-financeiro\/\"]}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/2024\/06\/06\/mdrt-realiza-reuniao-anual-abordando-ia-no-planejamento-financeiro\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/2024\/06\/06\/mdrt-realiza-reuniao-anual-abordando-ia-no-planejamento-financeiro\/#webpage\"},\"author\":{\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#\/schema\/person\/1b69c8cf325f0b7167f1b171f52df4af\"},\"headline\":\"MDRT realiza Reuni\\u00e3o Anual abordando IA\",\"datePublished\":\"2024-06-06T18:59:08+00:00\",\"dateModified\":\"2024-06-06T20:04:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/2024\/06\/06\/mdrt-realiza-reuniao-anual-abordando-ia-no-planejamento-financeiro\/#webpage\"},\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#organization\"},\"image\":{\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/2024\/06\/06\/mdrt-realiza-reuniao-anual-abordando-ia-no-planejamento-financeiro\/#primaryimage\"},\"keywords\":\"Canad\\u00e1,Intelig\\u00eancia Artificial,MDRT,planejamento financeiro,reuni\\u00e3o anual,seguro de vida\",\"articleSection\":\"MDRT Brasil\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/insurancecorp.com.br\/pt\/2024\/06\/06\/mdrt-realiza-reuniao-anual-abordando-ia-no-planejamento-financeiro\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#\/schema\/person\/1b69c8cf325f0b7167f1b171f52df4af\",\"name\":\"Publica\\u00e7\\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/17226f1f60486eb25d4c6b301ffed37f?s=96&d=mm&r=g\",\"caption\":\"Publica\\u00e7\\u00e3o\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/posts\/55465"}],"collection":[{"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/comments?post=55465"}],"version-history":[{"count":3,"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/posts\/55465\/revisions"}],"predecessor-version":[{"id":55511,"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/posts\/55465\/revisions\/55511"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/media\/55472"}],"wp:attachment":[{"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/media?parent=55465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/categories?post=55465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/tags?post=55465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}