{"id":36400,"date":"2022-08-08T14:43:27","date_gmt":"2022-08-08T17:43:27","guid":{"rendered":"https:\/\/insurancecorp.com.br\/pt\/?p=36400"},"modified":"2022-08-08T14:43:27","modified_gmt":"2022-08-08T17:43:27","slug":"europ-assistance-oferece-servico-de-protecao-digital","status":"publish","type":"post","link":"https:\/\/insurancecorp.com.br\/pt\/2022\/08\/08\/europ-assistance-oferece-servico-de-protecao-digital\/","title":{"rendered":"Europ Assistance oferece servi\u00e7o de \u2018Prote\u00e7\u00e3o Digital\u2019"},"content":{"rendered":"<p>O aumento da digitaliza\u00e7\u00e3o de servi\u00e7os e do consumo pela internet por conta da pandemia contribuiu tamb\u00e9m para o crescimento do n\u00famero de cibercrimes. Um levantamento recente feito pelo Centro de Reclama\u00e7\u00f5es de Crimes pela Internet do Federal Bureau of Investigation (FBI) aponta que houve uma eleva\u00e7\u00e3o de 7% nesse tipo de crime em compara\u00e7\u00e3o a 2020.<\/p>\n<p>Ainda segundo o org\u00e3o norte-americano, as potenciais perdas causadas por crimes cometidos na internet devem chegar a US$ 7 bilh\u00f5es, somente nos Estados Unidos. Entre os principais delitos est\u00e3o phishing e vishing (golpes que induzem as pessoas a fazer coisas que elas acreditam ser de verdade), smishing (uso de SMS e phising) e pharming (roubo de dados confidenciais).<\/p>\n<p>Aqui no Brasil o cen\u00e1rio se repete, mas as pr\u00e1ticas criminosas mais comuns envolvem ainda fraude banc\u00e1ria, roubo de identidade e invas\u00e3o cibern\u00e9tica. Com tantas potenciais amea\u00e7as ao mundo virtual, a Europ Assistance Brasil (EABR) desenvolveu um produto chamado \u2018Prote\u00e7\u00e3o Digital\u201d, uma solu\u00e7\u00e3o inovadora que atende \u00e0 crescente preocupa\u00e7\u00e3o do consumidor, especialmente aquele que faz compras pela internet.<\/p>\n<p>Por meio de uma plataforma, o servi\u00e7o promove a\u00e7\u00f5es preventivas contra roubos online atrav\u00e9s de softwares que podem ser instalados em diferentes equipamentos como computadores, tablets e smartphones, ocupando lacunas deixadas pelos antivirus tradicionais.<\/p>\n<p>Entre as tecnologias oferecidas est\u00e3o servi\u00e7os de criptografia de dados durante a navega\u00e7\u00e3o, o monitoramento de dados pessoais, o envio de alertas de poss\u00edveis riscos para o roubo de dados, al\u00e9m de uma helpline (central de atendimento para ajuda e tomada de medidas, em caso de identidade comprometida) com orienta\u00e7\u00f5es aos usu\u00e1rios.<\/p>\n<p>Os principais benef\u00edcios para os clientes envolvem orienta\u00e7\u00f5es precisas para uma navega\u00e7\u00e3o segura na Internet; o respaldo de ferramentas simples e efetivas; e informa\u00e7\u00f5es sobre exposi\u00e7\u00e3o e mitiga\u00e7\u00e3o de riscos. J\u00e1 para os parceiros comerciais, o \u2018Prote\u00e7\u00e3o Digital\u2019 \u00e9 um servi\u00e7o relevante, que possibilita intera\u00e7\u00f5es frequentes com os clientes por meio de plataforma personalizada com marca pr\u00f3pria, refor\u00e7ando a identidade e fidelizando os clientes.<\/p>\n<p>\u201cJunto ao aumento de compras online, precisamos lembrar que ao mesmo tempo existe um crescimento da nossa vulnerabilidade de exposi\u00e7\u00e3o de dados pessoais, o que compromete senhas, contas banc\u00e1rias, registros armazenados no celular, informa\u00e7\u00f5es m\u00e9dicas e pessoais, ente outras coisas\u201d, explica Rogerio Guandalini, diretor de Vendas e Marketing da Europ Assistance Brasil.<\/p>\n<p>De acordo com ele, as pessoas ficam desprotegidas porque n\u00e3o tem o costume de atualizar suas senhas na internet e n\u00e3o passam antiv\u00edrus em seus equipamentos, especialmente o telefone celular. \u201cPor isso \u00e9 t\u00e3o importante contar com o servi\u00e7o de prote\u00e7\u00e3o digital de dados\u201d, refor\u00e7a Guandalini.<\/p>\n<p>A utiliza\u00e7\u00e3o do servi\u00e7o \u00e9 bastante f\u00e1cil. O cliente entra no portal da EABR e digita seu e-mail e senha para fazer login. Feito isso, basta acessar na tela principal o painel de controle para definir quais das suas informa\u00e7\u00f5es ser\u00e3o monitoradas, que o sistema faz todo o resto, acompanhando o cliente na web, deepweb e darkweb; e gerando alertas quando necess\u00e1rio.<\/p>\n<p><strong>Ag\u00eancia Pauta Vip<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O aumento da digitaliza\u00e7\u00e3o de servi\u00e7os e do consumo pela internet por conta da pandemia contribuiu tamb\u00e9m para o crescimento do n\u00famero de cibercrimes. Um levantamento recente feito pelo Centro de Reclama\u00e7\u00f5es de Crimes pela Internet do Federal Bureau of Investigation (FBI) aponta que houve uma eleva\u00e7\u00e3o de 7% nesse tipo de crime em compara\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":36406,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4279],"tags":[5256,1534,5255,1536],"jetpack_featured_media_url":"https:\/\/insurancecorp.com.br\/pt\/wp-content\/uploads\/2022\/08\/Bidu-8-scaled.jpg","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v14.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Europ Assistance oferece servi\u00e7o de \u2018Prote\u00e7\u00e3o Digital\u2019 | Revista Insurance Corp | PT-BR<\/title>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<meta name=\"googlebot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta name=\"bingbot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/insurancecorp.com.br\/pt\/2022\/08\/08\/europ-assistance-oferece-servico-de-protecao-digital\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Europ Assistance oferece servi\u00e7o de \u2018Prote\u00e7\u00e3o Digital\u2019 | Revista Insurance Corp | PT-BR\" \/>\n<meta property=\"og:description\" content=\"O aumento da digitaliza\u00e7\u00e3o de servi\u00e7os e do consumo pela internet por conta da pandemia contribuiu tamb\u00e9m para o crescimento do n\u00famero de cibercrimes. Um levantamento recente feito pelo Centro de Reclama\u00e7\u00f5es de Crimes pela Internet do Federal Bureau of Investigation (FBI) aponta que houve uma eleva\u00e7\u00e3o de 7% nesse tipo de crime em compara\u00e7\u00e3o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/insurancecorp.com.br\/pt\/2022\/08\/08\/europ-assistance-oferece-servico-de-protecao-digital\/\" \/>\n<meta property=\"og:site_name\" content=\"Revista Insurance Corp | PT-BR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RevistaInsuranceCorp\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-08T17:43:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/insurancecorp.com.br\/pt\/wp-content\/uploads\/2022\/08\/Bidu-8-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#organization\",\"name\":\"Revista Insurance Corp\",\"url\":\"https:\/\/insurancecorp.com.br\/pt\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/RevistaInsuranceCorp\/\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#logo\",\"inLanguage\":\"pt-BR\",\"url\":\"\",\"caption\":\"Revista Insurance Corp\"},\"image\":{\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#website\",\"url\":\"https:\/\/insurancecorp.com.br\/pt\/\",\"name\":\"Revista Insurance Corp | PT-BR\",\"description\":\"A \\u00fanica revista bil\\u00edngue voltada ao mercado de seguro.\",\"publisher\":{\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/insurancecorp.com.br\/pt\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/2022\/08\/08\/europ-assistance-oferece-servico-de-protecao-digital\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/insurancecorp.com.br\/pt\/wp-content\/uploads\/2022\/08\/Bidu-8-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/2022\/08\/08\/europ-assistance-oferece-servico-de-protecao-digital\/#webpage\",\"url\":\"https:\/\/insurancecorp.com.br\/pt\/2022\/08\/08\/europ-assistance-oferece-servico-de-protecao-digital\/\",\"name\":\"Europ Assistance oferece servi\\u00e7o de \\u2018Prote\\u00e7\\u00e3o Digital\\u2019 | Revista Insurance Corp | PT-BR\",\"isPartOf\":{\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/2022\/08\/08\/europ-assistance-oferece-servico-de-protecao-digital\/#primaryimage\"},\"datePublished\":\"2022-08-08T17:43:27+00:00\",\"dateModified\":\"2022-08-08T17:43:27+00:00\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/insurancecorp.com.br\/pt\/2022\/08\/08\/europ-assistance-oferece-servico-de-protecao-digital\/\"]}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/2022\/08\/08\/europ-assistance-oferece-servico-de-protecao-digital\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/2022\/08\/08\/europ-assistance-oferece-servico-de-protecao-digital\/#webpage\"},\"author\":{\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#\/schema\/person\/1b69c8cf325f0b7167f1b171f52df4af\"},\"headline\":\"Europ Assistance oferece servi\\u00e7o de \\u2018Prote\\u00e7\\u00e3o Digital\\u2019\",\"datePublished\":\"2022-08-08T17:43:27+00:00\",\"dateModified\":\"2022-08-08T17:43:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/2022\/08\/08\/europ-assistance-oferece-servico-de-protecao-digital\/#webpage\"},\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#organization\"},\"image\":{\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/2022\/08\/08\/europ-assistance-oferece-servico-de-protecao-digital\/#primaryimage\"},\"keywords\":\"crimes virtuais,Europ Assistance Brasil,prote\\u00e7\\u00e3o digital,Rog\\u00e9rio Guandalini\",\"articleSection\":\"Europ Assistance Brasil\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/insurancecorp.com.br\/pt\/2022\/08\/08\/europ-assistance-oferece-servico-de-protecao-digital\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#\/schema\/person\/1b69c8cf325f0b7167f1b171f52df4af\",\"name\":\"Publica\\u00e7\\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/17226f1f60486eb25d4c6b301ffed37f?s=96&d=mm&r=g\",\"caption\":\"Publica\\u00e7\\u00e3o\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/posts\/36400"}],"collection":[{"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/comments?post=36400"}],"version-history":[{"count":3,"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/posts\/36400\/revisions"}],"predecessor-version":[{"id":36408,"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/posts\/36400\/revisions\/36408"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/media\/36406"}],"wp:attachment":[{"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/media?parent=36400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/categories?post=36400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/tags?post=36400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}