{"id":32669,"date":"2022-03-03T15:54:29","date_gmt":"2022-03-03T18:54:29","guid":{"rendered":"https:\/\/insurancecorp.com.br\/pt\/?p=32669"},"modified":"2022-03-03T15:54:29","modified_gmt":"2022-03-03T18:54:29","slug":"novo-trienio-com-perspectiva-de-crescimento","status":"publish","type":"post","link":"https:\/\/insurancecorp.com.br\/pt\/2022\/03\/03\/novo-trienio-com-perspectiva-de-crescimento\/","title":{"rendered":"Novo tri\u00eanio com perspectiva de crescimento"},"content":{"rendered":"<p>Diretor comercial da BrasilCap, Marcelo Gon\u00e7alves Farinha foi reeleito presidente da Federa\u00e7\u00e3o Nacional de Capitaliza\u00e7\u00e3o (FenaCap) e a diretoria para o tri\u00eanio 2022-24 e assumiu em 7 de fevereiro. A FenaCap, que neste ano completa 15 anos, representa as 16 empresas associadas no territ\u00f3rio nacional. A entidade tem sido estrat\u00e9gica no trabalho para o fortalecimento do segmento no mercado, contribuindo assim para o desenvolvimento econ\u00f4mico e social dos brasileiros.<br \/>\nEntre outros objetivos, a Federa\u00e7\u00e3o exerce a representa\u00e7\u00e3o pol\u00edtica e institucional do setor, promovendo a permanente defesa dos interesses do segmento; representa as associadas judicial ou extrajudicialmente; atua na cria\u00e7\u00e3o e aprimoramento de leis, normas e regulamentos que aumentem a efici\u00eancia deste segmento econ\u00f4mico. A nova gest\u00e3o tamb\u00e9m vem acompanhada de uma perspectiva positiva para o ano.<br \/>\nO mercado de capitaliza\u00e7\u00e3o deve registrar, em 2022, uma retomada sustent\u00e1vel em termos de crescimento em todas as regi\u00f5es do pa\u00eds. O resultado obtido at\u00e9 novembro de 2021 aponta para esse cen\u00e1rio. A receita atingiu R$ 22,18 bilh\u00f5es, alta de 6,25% no acumulado anual, se comparada a igual per\u00edodo de 2020. Para a FenaCap, isso refor\u00e7a a perspectiva de crescimento de dois d\u00edgitos para este ano.<br \/>\n\u201cNa pandemia, fomos compelidos a acelerar mudan\u00e7as que vinham ocorrendo em um ritmo mais lento e que, de uma hora para outra, nos imp\u00f4s um desafio at\u00e9 ent\u00e3o nunca vivenciado: a migra\u00e7\u00e3o do presencial para o digital. Isso foi poss\u00edvel por dois motivos: a capacidade demonstrada pelas empresas na adapta\u00e7\u00e3o \u00e0 nova realidade e a tradi\u00e7\u00e3o de resili\u00eancia do setor de capitaliza\u00e7\u00e3o\u201d, explica Marcelo Farinha.<br \/>\nOs produtos de capitaliza\u00e7\u00e3o constituem uma hist\u00f3ria de sucesso nos \u00faltimos 93 anos e, com resili\u00eancia, o segmento tem se reinventado e lan\u00e7ado produtos para atender \u00e0s mais variadas demandas. Um dos diferenciais da capitaliza\u00e7\u00e3o \u00e9 a sua capacidade de se acoplar a outros setores na cria\u00e7\u00e3o de novas solu\u00e7\u00f5es.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diretor comercial da BrasilCap, Marcelo Gon\u00e7alves Farinha foi reeleito presidente da Federa\u00e7\u00e3o Nacional de Capitaliza\u00e7\u00e3o (FenaCap) e a diretoria para o tri\u00eanio 2022-24 e assumiu em 7 de fevereiro. A FenaCap, que neste ano completa 15 anos, representa as 16 empresas associadas no territ\u00f3rio nacional. A entidade tem sido estrat\u00e9gica no trabalho para o fortalecimento [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1553],"tags":[1548],"jetpack_featured_media_url":"","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v14.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Novo tri\u00eanio com perspectiva de crescimento | Revista Insurance Corp | PT-BR<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Novo tri\u00eanio com perspectiva de crescimento | Revista Insurance Corp | PT-BR\" \/>\n<meta property=\"og:description\" content=\"Diretor comercial da BrasilCap, Marcelo Gon\u00e7alves Farinha foi reeleito presidente da Federa\u00e7\u00e3o Nacional de Capitaliza\u00e7\u00e3o (FenaCap) e a diretoria para o tri\u00eanio 2022-24 e assumiu em 7 de fevereiro. A FenaCap, que neste ano completa 15 anos, representa as 16 empresas associadas no territ\u00f3rio nacional. A entidade tem sido estrat\u00e9gica no trabalho para o fortalecimento [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/insurancecorp.com.br\/pt\/2022\/03\/03\/novo-trienio-com-perspectiva-de-crescimento\/\" \/>\n<meta property=\"og:site_name\" content=\"Revista Insurance Corp | PT-BR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RevistaInsuranceCorp\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-03T18:54:29+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#organization\",\"name\":\"Revista Insurance Corp\",\"url\":\"https:\/\/insurancecorp.com.br\/pt\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/RevistaInsuranceCorp\/\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#logo\",\"inLanguage\":\"pt-BR\",\"url\":\"\",\"caption\":\"Revista Insurance Corp\"},\"image\":{\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#website\",\"url\":\"https:\/\/insurancecorp.com.br\/pt\/\",\"name\":\"Revista Insurance Corp | PT-BR\",\"description\":\"A \\u00fanica revista bil\\u00edngue voltada ao mercado de seguro.\",\"publisher\":{\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/insurancecorp.com.br\/pt\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/2022\/03\/03\/novo-trienio-com-perspectiva-de-crescimento\/#webpage\",\"url\":\"https:\/\/insurancecorp.com.br\/pt\/2022\/03\/03\/novo-trienio-com-perspectiva-de-crescimento\/\",\"name\":\"Novo tri\\u00eanio com perspectiva de crescimento | Revista Insurance Corp | PT-BR\",\"isPartOf\":{\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#website\"},\"datePublished\":\"2022-03-03T18:54:29+00:00\",\"dateModified\":\"2022-03-03T18:54:29+00:00\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/insurancecorp.com.br\/pt\/2022\/03\/03\/novo-trienio-com-perspectiva-de-crescimento\/\"]}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/2022\/03\/03\/novo-trienio-com-perspectiva-de-crescimento\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/2022\/03\/03\/novo-trienio-com-perspectiva-de-crescimento\/#webpage\"},\"author\":{\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#\/schema\/person\/21976cdca11cce5fa256a89c80edd2e3\"},\"headline\":\"Novo tri\\u00eanio com perspectiva de crescimento\",\"datePublished\":\"2022-03-03T18:54:29+00:00\",\"dateModified\":\"2022-03-03T18:54:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/2022\/03\/03\/novo-trienio-com-perspectiva-de-crescimento\/#webpage\"},\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#organization\"},\"keywords\":\"edi\\u00e7\\u00e3o 40\",\"articleSection\":\"Federa\\u00e7\\u00f5es\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/insurancecorp.com.br\/pt\/2022\/03\/03\/novo-trienio-com-perspectiva-de-crescimento\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#\/schema\/person\/21976cdca11cce5fa256a89c80edd2e3\",\"name\":\"Revista Impressa IC - Portugu\\u00eas\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/insurancecorp.com.br\/pt\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d9c8ff9f0cc030bf62ce8bfff7ed5a36?s=96&d=mm&r=g\",\"caption\":\"Revista Impressa IC - Portugu\\u00eas\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/posts\/32669"}],"collection":[{"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/comments?post=32669"}],"version-history":[{"count":1,"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/posts\/32669\/revisions"}],"predecessor-version":[{"id":32670,"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/posts\/32669\/revisions\/32670"}],"wp:attachment":[{"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/media?parent=32669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/categories?post=32669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/insurancecorp.com.br\/pt\/wp-json\/wp\/v2\/tags?post=32669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}